{"id":1242,"date":"2020-05-01T19:33:20","date_gmt":"2020-05-01T10:33:20","guid":{"rendered":"https:\/\/life-lab.co.jp\/2020\/05\/01\/%e3%82%b4%e3%83%bc%e3%83%ab%e3%83%87%e3%83%b3%e3%82%a6%e3%82%a3%e3%83%bc%e3%82%af%e6%9c%9f%e9%96%93%e4%bc%91%e6%a5%ad%e3%81%ae%e3%81%8a%e7%9f%a5%e3%82%89%e3%81%9b-2\/"},"modified":"2024-02-22T16:23:39","modified_gmt":"2024-02-22T07:23:39","slug":"%e3%82%b4%e3%83%bc%e3%83%ab%e3%83%87%e3%83%b3%e3%82%a6%e3%82%a3%e3%83%bc%e3%82%af%e6%9c%9f%e9%96%93%e4%bc%91%e6%a5%ad%e3%81%ae%e3%81%8a%e7%9f%a5%e3%82%89%e3%81%9b-2","status":"publish","type":"post","link":"https:\/\/life-lab.co.jp\/en\/2020\/05\/01\/%e3%82%b4%e3%83%bc%e3%83%ab%e3%83%87%e3%83%b3%e3%82%a6%e3%82%a3%e3%83%bc%e3%82%af%e6%9c%9f%e9%96%93%e4%bc%91%e6%a5%ad%e3%81%ae%e3%81%8a%e7%9f%a5%e3%82%89%e3%81%9b-2\/","title":{"rendered":"Notice of closure during Golden Week"},"content":{"rendered":"<p>We apologize for any inconvenience, but Life Lab Inc. will be closed during the following period.<\/p>\n<p>\u25a0Golden Week holiday period<br \/>\nSaturday, May 2, 2020 - Wednesday, May 6, 2020<\/p>\n<p>We will respond to inquiries received during the holiday period starting from Thursday, May 7, 2020.<br \/>\nHumbly thank you for your understanding.<\/p>","protected":false},"excerpt":{"rendered":"<p>\u8aa0\u306b\u52dd\u624b\u306a\u304c\u3089\u3001\u682a\u5f0f\u4f1a\u793eLife Lab\u306f\u4ee5\u4e0b\u306e\u671f\u9593\u3092\u4f11\u696d\u3068\u3055\u305b\u3066\u3044\u305f\u3060\u304d\u307e\u3059\u3002 \u25a0\u30b4\u30fc\u30eb\u30c7\u30f3\u30a6\u30a3\u30fc\u30af\u4f11\u6687\u671f\u9593 [&hellip;]<\/p>\n","protected":false},"author":226050523,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_wpcom_ai_launchpad_first_post":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[120612,120604],"tags":[120607],"class_list":["post-1242","post","type-post","status-publish","format-standard","hentry","category-company","category-news","tag-company"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"\u8aa0\u306b\u52dd\u624b\u306a\u304c\u3089\u3001\u682a\u5f0f\u4f1a\u793eLife Lab\u306f\u4ee5\u4e0b\u306e\u671f\u9593\u3092\u4f11\u696d\u3068\u3055\u305b\u3066\u3044\u305f\u3060\u304d\u307e\u3059\u3002 \u25a0\u30b4\u30fc\u30eb\u30c7\u30f3\u30a6\u30a3\u30fc\u30af\u4f11\u6687\u671f\u9593\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Mori\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/life-lab.co.jp\/en\/2020\/05\/01\/%e3%82%b4%e3%83%bc%e3%83%ab%e3%83%87%e3%83%b3%e3%82%a6%e3%82%a3%e3%83%bc%e3%82%af%e6%9c%9f%e9%96%93%e4%bc%91%e6%a5%ad%e3%81%ae%e3%81%8a%e7%9f%a5%e3%82%89%e3%81%9b-2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Life Lab -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u30b4\u30fc\u30eb\u30c7\u30f3\u30a6\u30a3\u30fc\u30af\u671f\u9593\u4f11\u696d\u306e\u304a\u77e5\u3089\u305b - Life Lab\" \/>\n\t\t<meta property=\"og:description\" content=\"\u8aa0\u306b\u52dd\u624b\u306a\u304c\u3089\u3001\u682a\u5f0f\u4f1a\u793eLife Lab\u306f\u4ee5\u4e0b\u306e\u671f\u9593\u3092\u4f11\u696d\u3068\u3055\u305b\u3066\u3044\u305f\u3060\u304d\u307e\u3059\u3002 \u25a0\u30b4\u30fc\u30eb\u30c7\u30f3\u30a6\u30a3\u30fc\u30af\u4f11\u6687\u671f\u9593\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/life-lab.co.jp\/en\/2020\/05\/01\/%e3%82%b4%e3%83%bc%e3%83%ab%e3%83%87%e3%83%b3%e3%82%a6%e3%82%a3%e3%83%bc%e3%82%af%e6%9c%9f%e9%96%93%e4%bc%91%e6%a5%ad%e3%81%ae%e3%81%8a%e7%9f%a5%e3%82%89%e3%81%9b-2\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/life-lab.co.jp\/wp-content\/uploads\/2024\/02\/cropped-LifeLab.png?fit=2827%2C581&#038;ssl=1\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/i0.wp.com\/life-lab.co.jp\/wp-content\/uploads\/2024\/02\/cropped-LifeLab.png?fit=2827%2C581&#038;ssl=1\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-05-01T10:33:20+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-02-22T07:23:39+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u30b4\u30fc\u30eb\u30c7\u30f3\u30a6\u30a3\u30fc\u30af\u671f\u9593\u4f11\u696d\u306e\u304a\u77e5\u3089\u305b - Life Lab\" \/>\n\t\t<meta name=\"twitter:description\" content=\"\u8aa0\u306b\u52dd\u624b\u306a\u304c\u3089\u3001\u682a\u5f0f\u4f1a\u793eLife Lab\u306f\u4ee5\u4e0b\u306e\u671f\u9593\u3092\u4f11\u696d\u3068\u3055\u305b\u3066\u3044\u305f\u3060\u304d\u307e\u3059\u3002 \u25a0\u30b4\u30fc\u30eb\u30c7\u30f3\u30a6\u30a3\u30fc\u30af\u4f11\u6687\u671f\u9593\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/i0.wp.com\/life-lab.co.jp\/wp-content\/uploads\/2024\/02\/cropped-LifeLab.png?fit=2827%2C581&amp;ssl=1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/life-lab.co.jp\\\/en\\\/2020\\\/05\\\/01\\\/%e3%82%b4%e3%83%bc%e3%83%ab%e3%83%87%e3%83%b3%e3%82%a6%e3%82%a3%e3%83%bc%e3%82%af%e6%9c%9f%e9%96%93%e4%bc%91%e6%a5%ad%e3%81%ae%e3%81%8a%e7%9f%a5%e3%82%89%e3%81%9b-2\\\/#blogposting\",\"name\":\"\\u30b4\\u30fc\\u30eb\\u30c7\\u30f3\\u30a6\\u30a3\\u30fc\\u30af\\u671f\\u9593\\u4f11\\u696d\\u306e\\u304a\\u77e5\\u3089\\u305b - Life Lab\",\"headline\":\"\\u30b4\\u30fc\\u30eb\\u30c7\\u30f3\\u30a6\\u30a3\\u30fc\\u30af\\u671f\\u9593\\u4f11\\u696d\\u306e\\u304a\\u77e5\\u3089\\u305b\",\"author\":{\"@id\":\"https:\\\/\\\/life-lab.co.jp\\\/en\\\/author\\\/mori\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/life-lab.co.jp\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/life-lab.co.jp\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-LifeLab.png?fit=2827%2C581&ssl=1\",\"@id\":\"https:\\\/\\\/life-lab.co.jp\\\/en\\\/#articleImage\",\"width\":2827,\"height\":581},\"datePublished\":\"2020-05-01T19:33:20+09:00\",\"dateModified\":\"2024-02-22T16:23:39+09:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/life-lab.co.jp\\\/en\\\/2020\\\/05\\\/01\\\/%e3%82%b4%e3%83%bc%e3%83%ab%e3%83%87%e3%83%b3%e3%82%a6%e3%82%a3%e3%83%bc%e3%82%af%e6%9c%9f%e9%96%93%e4%bc%91%e6%a5%ad%e3%81%ae%e3%81%8a%e7%9f%a5%e3%82%89%e3%81%9b-2\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/life-lab.co.jp\\\/en\\\/2020\\\/05\\\/01\\\/%e3%82%b4%e3%83%bc%e3%83%ab%e3%83%87%e3%83%b3%e3%82%a6%e3%82%a3%e3%83%bc%e3%82%af%e6%9c%9f%e9%96%93%e4%bc%91%e6%a5%ad%e3%81%ae%e3%81%8a%e7%9f%a5%e3%82%89%e3%81%9b-2\\\/#webpage\"},\"articleSection\":\"COMPANY, news, COMPANY\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/life-lab.co.jp\\\/en\\\/2020\\\/05\\\/01\\\/%e3%82%b4%e3%83%bc%e3%83%ab%e3%83%87%e3%83%b3%e3%82%a6%e3%82%a3%e3%83%bc%e3%82%af%e6%9c%9f%e9%96%93%e4%bc%91%e6%a5%ad%e3%81%ae%e3%81%8a%e7%9f%a5%e3%82%89%e3%81%9b-2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/life-lab.co.jp\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/life-lab.co.jp\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/life-lab.co.jp\\\/en\\\/category\\\/news\\\/#listItem\",\"name\":\"news\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/life-lab.co.jp\\\/en\\\/category\\\/news\\\/#listItem\",\"position\":2,\"name\":\"news\",\"item\":\"https:\\\/\\\/life-lab.co.jp\\\/en\\\/category\\\/news\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/life-lab.co.jp\\\/en\\\/category\\\/news\\\/company\\\/#listItem\",\"name\":\"COMPANY\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/life-lab.co.jp\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/life-lab.co.jp\\\/en\\\/category\\\/news\\\/company\\\/#listItem\",\"position\":3,\"name\":\"COMPANY\",\"item\":\"https:\\\/\\\/life-lab.co.jp\\\/en\\\/category\\\/news\\\/company\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/life-lab.co.jp\\\/en\\\/2020\\\/05\\\/01\\\/%e3%82%b4%e3%83%bc%e3%83%ab%e3%83%87%e3%83%b3%e3%82%a6%e3%82%a3%e3%83%bc%e3%82%af%e6%9c%9f%e9%96%93%e4%bc%91%e6%a5%ad%e3%81%ae%e3%81%8a%e7%9f%a5%e3%82%89%e3%81%9b-2\\\/#listItem\",\"name\":\"\\u30b4\\u30fc\\u30eb\\u30c7\\u30f3\\u30a6\\u30a3\\u30fc\\u30af\\u671f\\u9593\\u4f11\\u696d\\u306e\\u304a\\u77e5\\u3089\\u305b\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/life-lab.co.jp\\\/en\\\/category\\\/news\\\/#listItem\",\"name\":\"news\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/life-lab.co.jp\\\/en\\\/2020\\\/05\\\/01\\\/%e3%82%b4%e3%83%bc%e3%83%ab%e3%83%87%e3%83%b3%e3%82%a6%e3%82%a3%e3%83%bc%e3%82%af%e6%9c%9f%e9%96%93%e4%bc%91%e6%a5%ad%e3%81%ae%e3%81%8a%e7%9f%a5%e3%82%89%e3%81%9b-2\\\/#listItem\",\"position\":4,\"name\":\"\\u30b4\\u30fc\\u30eb\\u30c7\\u30f3\\u30a6\\u30a3\\u30fc\\u30af\\u671f\\u9593\\u4f11\\u696d\\u306e\\u304a\\u77e5\\u3089\\u305b\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/life-lab.co.jp\\\/en\\\/category\\\/news\\\/company\\\/#listItem\",\"name\":\"COMPANY\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/life-lab.co.jp\\\/en\\\/#organization\",\"name\":\"Life Lab\",\"url\":\"https:\\\/\\\/life-lab.co.jp\\\/en\\\/\",\"telephone\":\"+81344000500\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/life-lab.co.jp\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-LifeLab.png?fit=2827%2C581&ssl=1\",\"@id\":\"https:\\\/\\\/life-lab.co.jp\\\/en\\\/2020\\\/05\\\/01\\\/%e3%82%b4%e3%83%bc%e3%83%ab%e3%83%87%e3%83%b3%e3%82%a6%e3%82%a3%e3%83%bc%e3%82%af%e6%9c%9f%e9%96%93%e4%bc%91%e6%a5%ad%e3%81%ae%e3%81%8a%e7%9f%a5%e3%82%89%e3%81%9b-2\\\/#organizationLogo\",\"width\":2827,\"height\":581},\"image\":{\"@id\":\"https:\\\/\\\/life-lab.co.jp\\\/en\\\/2020\\\/05\\\/01\\\/%e3%82%b4%e3%83%bc%e3%83%ab%e3%83%87%e3%83%b3%e3%82%a6%e3%82%a3%e3%83%bc%e3%82%af%e6%9c%9f%e9%96%93%e4%bc%91%e6%a5%ad%e3%81%ae%e3%81%8a%e7%9f%a5%e3%82%89%e3%81%9b-2\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/life-lab.co.jp\\\/en\\\/author\\\/mori\\\/#author\",\"url\":\"https:\\\/\\\/life-lab.co.jp\\\/en\\\/author\\\/mori\\\/\",\"name\":\"Mori\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/life-lab.co.jp\\\/en\\\/2020\\\/05\\\/01\\\/%e3%82%b4%e3%83%bc%e3%83%ab%e3%83%87%e3%83%b3%e3%82%a6%e3%82%a3%e3%83%bc%e3%82%af%e6%9c%9f%e9%96%93%e4%bc%91%e6%a5%ad%e3%81%ae%e3%81%8a%e7%9f%a5%e3%82%89%e3%81%9b-2\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a9b8dd95e8937f233b84800bb9981adce2f2b4f9beec1422c497d7dab59636f1?s=96&d=identicon&r=g\",\"width\":96,\"height\":96,\"caption\":\"Mori\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/life-lab.co.jp\\\/en\\\/2020\\\/05\\\/01\\\/%e3%82%b4%e3%83%bc%e3%83%ab%e3%83%87%e3%83%b3%e3%82%a6%e3%82%a3%e3%83%bc%e3%82%af%e6%9c%9f%e9%96%93%e4%bc%91%e6%a5%ad%e3%81%ae%e3%81%8a%e7%9f%a5%e3%82%89%e3%81%9b-2\\\/#webpage\",\"url\":\"https:\\\/\\\/life-lab.co.jp\\\/en\\\/2020\\\/05\\\/01\\\/%e3%82%b4%e3%83%bc%e3%83%ab%e3%83%87%e3%83%b3%e3%82%a6%e3%82%a3%e3%83%bc%e3%82%af%e6%9c%9f%e9%96%93%e4%bc%91%e6%a5%ad%e3%81%ae%e3%81%8a%e7%9f%a5%e3%82%89%e3%81%9b-2\\\/\",\"name\":\"\\u30b4\\u30fc\\u30eb\\u30c7\\u30f3\\u30a6\\u30a3\\u30fc\\u30af\\u671f\\u9593\\u4f11\\u696d\\u306e\\u304a\\u77e5\\u3089\\u305b - Life Lab\",\"description\":\"\\u8aa0\\u306b\\u52dd\\u624b\\u306a\\u304c\\u3089\\u3001\\u682a\\u5f0f\\u4f1a\\u793eLife Lab\\u306f\\u4ee5\\u4e0b\\u306e\\u671f\\u9593\\u3092\\u4f11\\u696d\\u3068\\u3055\\u305b\\u3066\\u3044\\u305f\\u3060\\u304d\\u307e\\u3059\\u3002 \\u25a0\\u30b4\\u30fc\\u30eb\\u30c7\\u30f3\\u30a6\\u30a3\\u30fc\\u30af\\u4f11\\u6687\\u671f\\u9593\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/life-lab.co.jp\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/life-lab.co.jp\\\/en\\\/2020\\\/05\\\/01\\\/%e3%82%b4%e3%83%bc%e3%83%ab%e3%83%87%e3%83%b3%e3%82%a6%e3%82%a3%e3%83%bc%e3%82%af%e6%9c%9f%e9%96%93%e4%bc%91%e6%a5%ad%e3%81%ae%e3%81%8a%e7%9f%a5%e3%82%89%e3%81%9b-2\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/life-lab.co.jp\\\/en\\\/author\\\/mori\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/life-lab.co.jp\\\/en\\\/author\\\/mori\\\/#author\"},\"datePublished\":\"2020-05-01T19:33:20+09:00\",\"dateModified\":\"2024-02-22T16:23:39+09:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/life-lab.co.jp\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/life-lab.co.jp\\\/en\\\/\",\"name\":\"Life Lab\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/life-lab.co.jp\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u30b4\u30fc\u30eb\u30c7\u30f3\u30a6\u30a3\u30fc\u30af\u671f\u9593\u4f11\u696d\u306e\u304a\u77e5\u3089\u305b - Life Lab","description":"We regret to inform you that Life Lab Co., Ltd. will be closed during the following period. \u25a0Golden Week holiday period","canonical_url":"https:\/\/life-lab.co.jp\/en\/2020\/05\/01\/%e3%82%b4%e3%83%bc%e3%83%ab%e3%83%87%e3%83%b3%e3%82%a6%e3%82%a3%e3%83%bc%e3%82%af%e6%9c%9f%e9%96%93%e4%bc%91%e6%a5%ad%e3%81%ae%e3%81%8a%e7%9f%a5%e3%82%89%e3%81%9b-2\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/life-lab.co.jp\/en\/2020\/05\/01\/%e3%82%b4%e3%83%bc%e3%83%ab%e3%83%87%e3%83%b3%e3%82%a6%e3%82%a3%e3%83%bc%e3%82%af%e6%9c%9f%e9%96%93%e4%bc%91%e6%a5%ad%e3%81%ae%e3%81%8a%e7%9f%a5%e3%82%89%e3%81%9b-2\/#blogposting","name":"\u30b4\u30fc\u30eb\u30c7\u30f3\u30a6\u30a3\u30fc\u30af\u671f\u9593\u4f11\u696d\u306e\u304a\u77e5\u3089\u305b - Life Lab","headline":"\u30b4\u30fc\u30eb\u30c7\u30f3\u30a6\u30a3\u30fc\u30af\u671f\u9593\u4f11\u696d\u306e\u304a\u77e5\u3089\u305b","author":{"@id":"https:\/\/life-lab.co.jp\/en\/author\/mori\/#author"},"publisher":{"@id":"https:\/\/life-lab.co.jp\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/life-lab.co.jp\/wp-content\/uploads\/2024\/02\/cropped-LifeLab.png?fit=2827%2C581&ssl=1","@id":"https:\/\/life-lab.co.jp\/en\/#articleImage","width":2827,"height":581},"datePublished":"2020-05-01T19:33:20+09:00","dateModified":"2024-02-22T16:23:39+09:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/life-lab.co.jp\/en\/2020\/05\/01\/%e3%82%b4%e3%83%bc%e3%83%ab%e3%83%87%e3%83%b3%e3%82%a6%e3%82%a3%e3%83%bc%e3%82%af%e6%9c%9f%e9%96%93%e4%bc%91%e6%a5%ad%e3%81%ae%e3%81%8a%e7%9f%a5%e3%82%89%e3%81%9b-2\/#webpage"},"isPartOf":{"@id":"https:\/\/life-lab.co.jp\/en\/2020\/05\/01\/%e3%82%b4%e3%83%bc%e3%83%ab%e3%83%87%e3%83%b3%e3%82%a6%e3%82%a3%e3%83%bc%e3%82%af%e6%9c%9f%e9%96%93%e4%bc%91%e6%a5%ad%e3%81%ae%e3%81%8a%e7%9f%a5%e3%82%89%e3%81%9b-2\/#webpage"},"articleSection":"COMPANY, news, COMPANY"},{"@type":"BreadcrumbList","@id":"https:\/\/life-lab.co.jp\/en\/2020\/05\/01\/%e3%82%b4%e3%83%bc%e3%83%ab%e3%83%87%e3%83%b3%e3%82%a6%e3%82%a3%e3%83%bc%e3%82%af%e6%9c%9f%e9%96%93%e4%bc%91%e6%a5%ad%e3%81%ae%e3%81%8a%e7%9f%a5%e3%82%89%e3%81%9b-2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/life-lab.co.jp\/en#listItem","position":1,"name":"Home","item":"https:\/\/life-lab.co.jp\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/life-lab.co.jp\/en\/category\/news\/#listItem","name":"news"}},{"@type":"ListItem","@id":"https:\/\/life-lab.co.jp\/en\/category\/news\/#listItem","position":2,"name":"news","item":"https:\/\/life-lab.co.jp\/en\/category\/news\/","nextItem":{"@type":"ListItem","@id":"https:\/\/life-lab.co.jp\/en\/category\/news\/company\/#listItem","name":"COMPANY"},"previousItem":{"@type":"ListItem","@id":"https:\/\/life-lab.co.jp\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/life-lab.co.jp\/en\/category\/news\/company\/#listItem","position":3,"name":"COMPANY","item":"https:\/\/life-lab.co.jp\/en\/category\/news\/company\/","nextItem":{"@type":"ListItem","@id":"https:\/\/life-lab.co.jp\/en\/2020\/05\/01\/%e3%82%b4%e3%83%bc%e3%83%ab%e3%83%87%e3%83%b3%e3%82%a6%e3%82%a3%e3%83%bc%e3%82%af%e6%9c%9f%e9%96%93%e4%bc%91%e6%a5%ad%e3%81%ae%e3%81%8a%e7%9f%a5%e3%82%89%e3%81%9b-2\/#listItem","name":"\u30b4\u30fc\u30eb\u30c7\u30f3\u30a6\u30a3\u30fc\u30af\u671f\u9593\u4f11\u696d\u306e\u304a\u77e5\u3089\u305b"},"previousItem":{"@type":"ListItem","@id":"https:\/\/life-lab.co.jp\/en\/category\/news\/#listItem","name":"news"}},{"@type":"ListItem","@id":"https:\/\/life-lab.co.jp\/en\/2020\/05\/01\/%e3%82%b4%e3%83%bc%e3%83%ab%e3%83%87%e3%83%b3%e3%82%a6%e3%82%a3%e3%83%bc%e3%82%af%e6%9c%9f%e9%96%93%e4%bc%91%e6%a5%ad%e3%81%ae%e3%81%8a%e7%9f%a5%e3%82%89%e3%81%9b-2\/#listItem","position":4,"name":"\u30b4\u30fc\u30eb\u30c7\u30f3\u30a6\u30a3\u30fc\u30af\u671f\u9593\u4f11\u696d\u306e\u304a\u77e5\u3089\u305b","previousItem":{"@type":"ListItem","@id":"https:\/\/life-lab.co.jp\/en\/category\/news\/company\/#listItem","name":"COMPANY"}}]},{"@type":"Organization","@id":"https:\/\/life-lab.co.jp\/en\/#organization","name":"Life Lab","url":"https:\/\/life-lab.co.jp\/en\/","telephone":"+81344000500","logo":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/life-lab.co.jp\/wp-content\/uploads\/2024\/02\/cropped-LifeLab.png?fit=2827%2C581&ssl=1","@id":"https:\/\/life-lab.co.jp\/en\/2020\/05\/01\/%e3%82%b4%e3%83%bc%e3%83%ab%e3%83%87%e3%83%b3%e3%82%a6%e3%82%a3%e3%83%bc%e3%82%af%e6%9c%9f%e9%96%93%e4%bc%91%e6%a5%ad%e3%81%ae%e3%81%8a%e7%9f%a5%e3%82%89%e3%81%9b-2\/#organizationLogo","width":2827,"height":581},"image":{"@id":"https:\/\/life-lab.co.jp\/en\/2020\/05\/01\/%e3%82%b4%e3%83%bc%e3%83%ab%e3%83%87%e3%83%b3%e3%82%a6%e3%82%a3%e3%83%bc%e3%82%af%e6%9c%9f%e9%96%93%e4%bc%91%e6%a5%ad%e3%81%ae%e3%81%8a%e7%9f%a5%e3%82%89%e3%81%9b-2\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/life-lab.co.jp\/en\/author\/mori\/#author","url":"https:\/\/life-lab.co.jp\/en\/author\/mori\/","name":"Mori","image":{"@type":"ImageObject","@id":"https:\/\/life-lab.co.jp\/en\/2020\/05\/01\/%e3%82%b4%e3%83%bc%e3%83%ab%e3%83%87%e3%83%b3%e3%82%a6%e3%82%a3%e3%83%bc%e3%82%af%e6%9c%9f%e9%96%93%e4%bc%91%e6%a5%ad%e3%81%ae%e3%81%8a%e7%9f%a5%e3%82%89%e3%81%9b-2\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a9b8dd95e8937f233b84800bb9981adce2f2b4f9beec1422c497d7dab59636f1?s=96&d=identicon&r=g","width":96,"height":96,"caption":"Mori"}},{"@type":"WebPage","@id":"https:\/\/life-lab.co.jp\/en\/2020\/05\/01\/%e3%82%b4%e3%83%bc%e3%83%ab%e3%83%87%e3%83%b3%e3%82%a6%e3%82%a3%e3%83%bc%e3%82%af%e6%9c%9f%e9%96%93%e4%bc%91%e6%a5%ad%e3%81%ae%e3%81%8a%e7%9f%a5%e3%82%89%e3%81%9b-2\/#webpage","url":"https:\/\/life-lab.co.jp\/en\/2020\/05\/01\/%e3%82%b4%e3%83%bc%e3%83%ab%e3%83%87%e3%83%b3%e3%82%a6%e3%82%a3%e3%83%bc%e3%82%af%e6%9c%9f%e9%96%93%e4%bc%91%e6%a5%ad%e3%81%ae%e3%81%8a%e7%9f%a5%e3%82%89%e3%81%9b-2\/","name":"\u30b4\u30fc\u30eb\u30c7\u30f3\u30a6\u30a3\u30fc\u30af\u671f\u9593\u4f11\u696d\u306e\u304a\u77e5\u3089\u305b - Life Lab","description":"\u8aa0\u306b\u52dd\u624b\u306a\u304c\u3089\u3001\u682a\u5f0f\u4f1a\u793eLife Lab\u306f\u4ee5\u4e0b\u306e\u671f\u9593\u3092\u4f11\u696d\u3068\u3055\u305b\u3066\u3044\u305f\u3060\u304d\u307e\u3059\u3002 \u25a0\u30b4\u30fc\u30eb\u30c7\u30f3\u30a6\u30a3\u30fc\u30af\u4f11\u6687\u671f\u9593","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/life-lab.co.jp\/en\/#website"},"breadcrumb":{"@id":"https:\/\/life-lab.co.jp\/en\/2020\/05\/01\/%e3%82%b4%e3%83%bc%e3%83%ab%e3%83%87%e3%83%b3%e3%82%a6%e3%82%a3%e3%83%bc%e3%82%af%e6%9c%9f%e9%96%93%e4%bc%91%e6%a5%ad%e3%81%ae%e3%81%8a%e7%9f%a5%e3%82%89%e3%81%9b-2\/#breadcrumblist"},"author":{"@id":"https:\/\/life-lab.co.jp\/en\/author\/mori\/#author"},"creator":{"@id":"https:\/\/life-lab.co.jp\/en\/author\/mori\/#author"},"datePublished":"2020-05-01T19:33:20+09:00","dateModified":"2024-02-22T16:23:39+09:00"},{"@type":"WebSite","@id":"https:\/\/life-lab.co.jp\/en\/#website","url":"https:\/\/life-lab.co.jp\/en\/","name":"Life Lab","inLanguage":"en-US","publisher":{"@id":"https:\/\/life-lab.co.jp\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Life Lab -","og:type":"article","og:title":"\u30b4\u30fc\u30eb\u30c7\u30f3\u30a6\u30a3\u30fc\u30af\u671f\u9593\u4f11\u696d\u306e\u304a\u77e5\u3089\u305b - Life Lab","og:description":"\u8aa0\u306b\u52dd\u624b\u306a\u304c\u3089\u3001\u682a\u5f0f\u4f1a\u793eLife Lab\u306f\u4ee5\u4e0b\u306e\u671f\u9593\u3092\u4f11\u696d\u3068\u3055\u305b\u3066\u3044\u305f\u3060\u304d\u307e\u3059\u3002 \u25a0\u30b4\u30fc\u30eb\u30c7\u30f3\u30a6\u30a3\u30fc\u30af\u4f11\u6687\u671f\u9593","og:url":"https:\/\/life-lab.co.jp\/en\/2020\/05\/01\/%e3%82%b4%e3%83%bc%e3%83%ab%e3%83%87%e3%83%b3%e3%82%a6%e3%82%a3%e3%83%bc%e3%82%af%e6%9c%9f%e9%96%93%e4%bc%91%e6%a5%ad%e3%81%ae%e3%81%8a%e7%9f%a5%e3%82%89%e3%81%9b-2\/","og:image":"https:\/\/i0.wp.com\/life-lab.co.jp\/wp-content\/uploads\/2024\/02\/cropped-LifeLab.png?fit=2827%2C581&#038;ssl=1","og:image:secure_url":"https:\/\/i0.wp.com\/life-lab.co.jp\/wp-content\/uploads\/2024\/02\/cropped-LifeLab.png?fit=2827%2C581&#038;ssl=1","article:published_time":"2020-05-01T10:33:20+00:00","article:modified_time":"2024-02-22T07:23:39+00:00","twitter:card":"summary_large_image","twitter:title":"\u30b4\u30fc\u30eb\u30c7\u30f3\u30a6\u30a3\u30fc\u30af\u671f\u9593\u4f11\u696d\u306e\u304a\u77e5\u3089\u305b - Life Lab","twitter:description":"\u8aa0\u306b\u52dd\u624b\u306a\u304c\u3089\u3001\u682a\u5f0f\u4f1a\u793eLife Lab\u306f\u4ee5\u4e0b\u306e\u671f\u9593\u3092\u4f11\u696d\u3068\u3055\u305b\u3066\u3044\u305f\u3060\u304d\u307e\u3059\u3002 \u25a0\u30b4\u30fc\u30eb\u30c7\u30f3\u30a6\u30a3\u30fc\u30af\u4f11\u6687\u671f\u9593","twitter:image":"https:\/\/i0.wp.com\/life-lab.co.jp\/wp-content\/uploads\/2024\/02\/cropped-LifeLab.png?fit=2827%2C581&ssl=1"},"aioseo_meta_data":{"post_id":"1242","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-02-28 05:13:50","updated":"2025-06-03 22:07:34","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/life-lab.co.jp\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/life-lab.co.jp\/en\/category\/news\/\" title=\"news\">news<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/life-lab.co.jp\/en\/category\/news\/company\/\" title=\"COMPANY\">COMPANY<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u30b4\u30fc\u30eb\u30c7\u30f3\u30a6\u30a3\u30fc\u30af\u671f\u9593\u4f11\u696d\u306e\u304a\u77e5\u3089\u305b\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/life-lab.co.jp\/en"},{"label":"news","link":"https:\/\/life-lab.co.jp\/en\/category\/news\/"},{"label":"COMPANY","link":"https:\/\/life-lab.co.jp\/en\/category\/news\/company\/"},{"label":"\u30b4\u30fc\u30eb\u30c7\u30f3\u30a6\u30a3\u30fc\u30af\u671f\u9593\u4f11\u696d\u306e\u304a\u77e5\u3089\u305b","link":"https:\/\/life-lab.co.jp\/en\/2020\/05\/01\/%e3%82%b4%e3%83%bc%e3%83%ab%e3%83%87%e3%83%b3%e3%82%a6%e3%82%a3%e3%83%bc%e3%82%af%e6%9c%9f%e9%96%93%e4%bc%91%e6%a5%ad%e3%81%ae%e3%81%8a%e7%9f%a5%e3%82%89%e3%81%9b-2\/"}],"jetpack_publicize_connections":[],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false,"newspack-article-block-landscape-large":false,"newspack-article-block-portrait-large":false,"newspack-article-block-square-large":false,"newspack-article-block-landscape-medium":false,"newspack-article-block-portrait-medium":false,"newspack-article-block-square-medium":false,"newspack-article-block-landscape-intermediate":false,"newspack-article-block-portrait-intermediate":false,"newspack-article-block-square-intermediate":false,"newspack-article-block-landscape-small":false,"newspack-article-block-portrait-small":false,"newspack-article-block-square-small":false,"newspack-article-block-landscape-tiny":false,"newspack-article-block-portrait-tiny":false,"newspack-article-block-square-tiny":false,"newspack-article-block-uncropped":false},"uagb_author_info":{"display_name":"Mori","author_link":"https:\/\/life-lab.co.jp\/en\/author\/mori\/"},"uagb_comment_info":0,"uagb_excerpt":"\u8aa0\u306b\u52dd\u624b\u306a\u304c\u3089\u3001\u682a\u5f0f\u4f1a\u793eLife Lab\u306f\u4ee5\u4e0b\u306e\u671f\u9593\u3092\u4f11\u696d\u3068\u3055\u305b\u3066\u3044\u305f\u3060\u304d\u307e\u3059\u3002 \u25a0\u30b4\u30fc\u30eb\u30c7\u30f3\u30a6\u30a3\u30fc\u30af\u4f11\u6687\u671f\u9593&hellip;","jetpack_likes_enabled":false,"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/peCLks-k2","jetpack-related-posts":[],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/life-lab.co.jp\/en\/wp-json\/wp\/v2\/posts\/1242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/life-lab.co.jp\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/life-lab.co.jp\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/life-lab.co.jp\/en\/wp-json\/wp\/v2\/users\/226050523"}],"replies":[{"embeddable":true,"href":"https:\/\/life-lab.co.jp\/en\/wp-json\/wp\/v2\/comments?post=1242"}],"version-history":[{"count":1,"href":"https:\/\/life-lab.co.jp\/en\/wp-json\/wp\/v2\/posts\/1242\/revisions"}],"predecessor-version":[{"id":1853,"href":"https:\/\/life-lab.co.jp\/en\/wp-json\/wp\/v2\/posts\/1242\/revisions\/1853"}],"wp:attachment":[{"href":"https:\/\/life-lab.co.jp\/en\/wp-json\/wp\/v2\/media?parent=1242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/life-lab.co.jp\/en\/wp-json\/wp\/v2\/categories?post=1242"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/life-lab.co.jp\/en\/wp-json\/wp\/v2\/tags?post=1242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}